{"id":24,"date":"2008-01-19T18:31:49","date_gmt":"2008-01-19T16:31:49","guid":{"rendered":"http:\/\/pieter.wigleven.com\/it\/wp-content\/uploads\/2008\/01\/6-hyperv2.jpg"},"modified":"2008-01-19T18:31:49","modified_gmt":"2008-01-19T16:31:49","slug":"hyper-v-dialog-2","status":"inherit","type":"attachment","link":"https:\/\/pieter.wigleven.com\/it\/archives\/19\/hyper-v-dialog-2","title":{"rendered":"Hyper-V Dialog 2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-24","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pieter.wigleven.com\/it\/wp-content\/uploads\/2008\/01\/6-hyperv2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/pieter.wigleven.com\/it\/wp-content\/uploads\/2008\/01\/6-hyperv2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":780,"height":587,"hwstring_small":"height='96' width='127'","file":"\/home\/pieter\/public_html\/it\/wp-content\/uploads\/2008\/01\/6-hyperv2.jpg","thumb":"6-hyperv2.thumbnail.jpg","sizes":{}},"post":19,"source_url":"https:\/\/pieter.wigleven.com\/it\/wp-content\/uploads\/2008\/01\/6-hyperv2.jpg","filename":"6-hyperv2.jpg","filesize":null,"_links":{"self":[{"href":"https:\/\/pieter.wigleven.com\/it\/wp-json\/wp\/v2\/media\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pieter.wigleven.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pieter.wigleven.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pieter.wigleven.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pieter.wigleven.com\/it\/wp-json\/wp\/v2\/comments?post=24"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":19,"href":"https:\/\/pieter.wigleven.com\/it\/wp-json\/wp\/v2\/posts\/19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}